{"id":278,"date":"2012-03-15T21:07:06","date_gmt":"2012-03-15T20:07:06","guid":{"rendered":"http:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg"},"modified":"2012-03-15T21:07:06","modified_gmt":"2012-03-15T20:07:06","slug":"woordenboek","status":"inherit","type":"attachment","link":"https:\/\/orcazine.com\/nl\/contribution\/woordenboek\/","title":{"rendered":"woordenboek"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":{"_exactmetrics_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>woordenboek - ORCAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"woordenboek - ORCAZINE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\" \/>\n<meta property=\"og:site_name\" content=\"ORCAZINE\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"384\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\",\"url\":\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\",\"name\":\"woordenboek - ORCAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/orcazine.com\/#website\"},\"datePublished\":\"2012-03-15T20:07:06+00:00\",\"dateModified\":\"2012-03-15T20:07:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/orcazine.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Do you want to help?\",\"item\":\"https:\/\/orcazine.com\/contribution\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"woordenboek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/orcazine.com\/#website\",\"url\":\"https:\/\/orcazine.com\/\",\"name\":\"ORCAZINE\",\"description\":\"The magazine for orcaholics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/orcazine.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"woordenboek - ORCAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","og_locale":"nl_NL","og_type":"article","og_title":"woordenboek - ORCAZINE","og_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","og_site_name":"ORCAZINE","og_image":[{"width":384,"height":500,"url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","name":"woordenboek - ORCAZINE","isPartOf":{"@id":"https:\/\/orcazine.com\/#website"},"datePublished":"2012-03-15T20:07:06+00:00","dateModified":"2012-03-15T20:07:06+00:00","breadcrumb":{"@id":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orcazine.com\/"},{"@type":"ListItem","position":2,"name":"Do you want to help?","item":"https:\/\/orcazine.com\/contribution\/"},{"@type":"ListItem","position":3,"name":"woordenboek"}]},{"@type":"WebSite","@id":"https:\/\/orcazine.com\/#website","url":"https:\/\/orcazine.com\/","name":"ORCAZINE","description":"The magazine for orcaholics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orcazine.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"300\" src=\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-230x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-230x300.jpg 230w, https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg 384w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":384,"height":500,"file":"2012\/02\/woordenboek.jpg","sizes":{"thumbnail":{"file":"woordenboek-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-150x150.jpg"},"medium":{"file":"woordenboek-230x300.jpg","width":230,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-230x300.jpg"},"cb-100-65":{"file":"woordenboek-100x65.jpg","width":100,"height":65,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-100x65.jpg"},"cb-260-170":{"file":"woordenboek-260x170.jpg","width":260,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-260x170.jpg"},"cb-360-490":{"file":"woordenboek-360x490.jpg","width":360,"height":490,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-360x490.jpg"},"cb-360-240":{"file":"woordenboek-360x240.jpg","width":360,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-360x240.jpg"},"cb-378-300":{"file":"woordenboek-378x300.jpg","width":378,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-378x300.jpg"},"cb-759-300":{"file":"woordenboek-384x300.jpg","width":384,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-384x300.jpg"},"cb-759-500":{"file":"woordenboek-384x500.jpg","width":384,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-384x500.jpg"},"post-thumbnail":{"file":"woordenboek-125x125.jpg","width":125,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek-125x125.jpg"},"full":{"file":"woordenboek.jpg","width":384,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":1}},"post":82,"source_url":"https:\/\/orcazine.com\/wp-content\/uploads\/2012\/02\/woordenboek.jpg","_links":{"self":[{"href":"https:\/\/orcazine.com\/nl\/wp-json\/wp\/v2\/media\/278"}],"collection":[{"href":"https:\/\/orcazine.com\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/orcazine.com\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/orcazine.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orcazine.com\/nl\/wp-json\/wp\/v2\/comments?post=278"}]}}